{"id":29367,"date":"2026-03-30T00:00:00","date_gmt":"2026-03-29T15:00:00","guid":{"rendered":"https:\/\/iriomote-tour.com\/?post_type=plan&#038;p=29367"},"modified":"2026-05-11T10:42:24","modified_gmt":"2026-05-11T01:42:24","slug":"setplan-543","status":"publish","type":"plan","link":"https:\/\/iriomote-tour.com\/zh_cn\/plan\/setplan-543","title":{"rendered":"\u65c5\u884c\u56e2 \u9650\u91cf\u6298\u6263] \u897f\u8868\u5c9b\u21c6\u77f3\u57a3\u5c9b\u9644\u8239\u7968\u2605\u82ad\u62c9\u82cf\u5c9b\u6d6e\u6f5c\u6eaa\u964d\u4e4b\u65c5\u2605\u514d\u8d39\u7167\u7247 (No.543)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":38,"featured_media":29557,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-29367","plan","type-plan","status-publish","has-post-thumbnail","hentry","plan_genre-oneday-tour","plan_genre-ferry_activity","plan_genre-famous-plan-ranking","plan_genre-snokel","plan_genre-activty","plan_genre-canyoning","plan_genre-held-in-uehara-port","plan_genre-set-plan","plan_genre-barasu-tour","plan_genre-group-travel","plan_genre-maruyu","plan_genre-one-day","plan_spot-barasu-island","plan_watching-turtle","plan_watching-tropical-fishing","plan_scene-couple-tour","plan_scene-family-tour","plan_scene-girls-tour","plan_scene-boys-tour","plan_scene-students-tour","plan_scene-employees-tour","plan_scene-one-person-tour","plan_scene-group-tour","plan_scene-honeymoon-tour","plan_season-all-season","plan_season-spring","plan_season-summer","plan_season-fall","plan_season-winter","plan_timeframe-oneday","plan_particular-includes-ferry-ticket","plan_particular-prescription-goggles","plan_particular-instant-booking-available","plan_particular-previous-day-reservation","plan_particular-rainy-day","plan_particular-for-beginners","plan_particular-maruyu","plan_particular-multilingual-tour","plan_particular-free-photo","plan_particular-popular-guide","plan_particular-group-ok","plan_particular-shower-available","plan_particular-day-trip","plan_particular-6-9-year-old-participation","plan_particular-all-inclusive-price","plan_particular-on-site-payment-with-credit-card","plan_label-maruyu","plan_label-original","plan_label-ferry-ticket","plan_label-limited-discount","plan_label-limited-plan"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/plan-api\/29367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/plan-api"}],"about":[{"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/types\/plan"}],"author":[{"embeddable":true,"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/comments?post=29367"}],"version-history":[{"count":11,"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/plan-api\/29367\/revisions"}],"predecessor-version":[{"id":33360,"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/plan-api\/29367\/revisions\/33360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/media\/29557"}],"wp:attachment":[{"href":"https:\/\/iriomote-tour.com\/zh_cn\/wp-json\/wp\/v2\/media?parent=29367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}